{"id":237817,"date":"2026-04-15T19:49:45","date_gmt":"2026-04-15T23:49:45","guid":{"rendered":"https:\/\/thelocalgirl.com\/bergen\/event\/ryan-flannery-live-music-at-steel-wheel-tavern\/"},"modified":"2026-04-17T12:26:46","modified_gmt":"2026-04-17T16:26:46","slug":"ryan-flannery-live-music-at-steel-wheel-tavern","status":"publish","type":"event","link":"https:\/\/thelocalgirl.com\/bergen\/event\/ryan-flannery-live-music-at-steel-wheel-tavern\/","title":{"rendered":"Ryan Flannery &#8211; Live Music! at Steel Wheel Tavern"},"content":{"rendered":"<p>Enjoy Live Music at The Steel Wheel Tavern featuring&#8230;<\/p>\n<p>Ryan Flannery &#8211; Singer\/Songwriter from Dumont, NJ. Singer\/Guitarist for NJ Hard Rock band, Strive.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enjoy Live Music at The Steel Wheel Tavern featuring&#8230; Ryan Flannery &#8211; Singer\/Songwriter from Dumont, NJ. Singer\/Guitarist for NJ Hard Rock band,&hellip;<\/p>\n","protected":false},"author":422,"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","_links_to":"","_links_to_target":"","submission_name":"Ryan Flannery - Live Music! at Steel Wheel Tavern","email_address":"","business_name":"Steel Wheel Tavern","event_location":"51 N Broad St, Ridgewood, NJ 07450","event_link":"https:\/\/www.steelwheeltavern.com\/events\/ryan-flannery-live-music-36d10607","event_price":"Free","featured_event":"","event_total":"","event_coupon":"","event_start_date":"20260418","event_start_time":"18:00:00","event_start_timestamp":"1776535200","event_end_date":"20260418","event_end_time":"21:00:00","event_end_timestamp":"1776470400","event_duration":"","event_recurrence_end_timestamp":"1776546000","event_repeat_frequency":"","event_repeat_ends":"","event_repeat_date":"","event_repeat_occurrences":"","event_image":"https:\/\/popmenucloud.com\/cdn-cgi\/image\/width%3D2400%2Cheight%3D2400%2Cfit%3Dscale-down%2Cformat%3Dauto%2Cquality%3D60\/qscktxur\/bf855743-456e-4bc0-b672-1e8170350a1d.jpg","all_day_event":"0","venue_name":"Steel Wheel Tavern","admin_city":"Ridgewood","wp_last_modified_info":"April 13, 2026 @ 3:25 pm","event_import_post_id":"","source_guid":"https:\/\/thelocalgirl.com\/calendar\/?post_type=event&#038;p=234089"},"categories":[8834,9823,9794],"tags":[],"class_list":["post-237817","event","type-event","status-publish","hentry","category-entertainment","category-free","category-the-bergen-county-girl-calendar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ryan Flannery - Live Music! at Steel Wheel Tavern - The Bergen County Girl<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ryan Flannery - Live Music! at Steel Wheel Tavern\" \/>\n<meta property=\"og:description\" content=\"Enjoy Live Music at The Steel Wheel Tavern featuring&#8230; Ryan Flannery &#8211; Singer\/Songwriter from Dumont, NJ. Singer\/Guitarist for NJ Hard Rock band,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thelocalgirl.com\/bergen\/event\/ryan-flannery-live-music-at-steel-wheel-tavern\/\" \/>\n<meta property=\"og:site_name\" content=\"The Bergen County Girl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T16:26:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thelocalgirl.com\\\/bergen\\\/event\\\/ryan-flannery-live-music-at-steel-wheel-tavern\\\/\",\"url\":\"https:\\\/\\\/thelocalgirl.com\\\/bergen\\\/event\\\/ryan-flannery-live-music-at-steel-wheel-tavern\\\/\",\"name\":\"Ryan Flannery - Live Music! at Steel Wheel Tavern - The Bergen County Girl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thelocalgirl.com\\\/bergen\\\/#website\"},\"datePublished\":\"2026-04-15T23:49:45+00:00\",\"dateModified\":\"2026-04-17T16:26:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thelocalgirl.com\\\/bergen\\\/event\\\/ryan-flannery-live-music-at-steel-wheel-tavern\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thelocalgirl.com\\\/bergen\\\/event\\\/ryan-flannery-live-music-at-steel-wheel-tavern\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thelocalgirl.com\\\/bergen\\\/event\\\/ryan-flannery-live-music-at-steel-wheel-tavern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thelocalgirl.com\\\/bergen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ryan Flannery &#8211; Live Music! at Steel Wheel Tavern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thelocalgirl.com\\\/bergen\\\/#website\",\"url\":\"https:\\\/\\\/thelocalgirl.com\\\/bergen\\\/\",\"name\":\"The Bergen County Girl\",\"description\":\"A lifestyle site dedicated to all things Local \u2014 with a New Jersey twist.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thelocalgirl.com\\\/bergen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ryan Flannery - Live Music! at Steel Wheel Tavern - The Bergen County Girl","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Ryan Flannery - Live Music! at Steel Wheel Tavern","og_description":"Enjoy Live Music at The Steel Wheel Tavern featuring&#8230; Ryan Flannery &#8211; Singer\/Songwriter from Dumont, NJ. Singer\/Guitarist for NJ Hard Rock band,&hellip;","og_url":"https:\/\/thelocalgirl.com\/bergen\/event\/ryan-flannery-live-music-at-steel-wheel-tavern\/","og_site_name":"The Bergen County Girl","article_modified_time":"2026-04-17T16:26:46+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thelocalgirl.com\/bergen\/event\/ryan-flannery-live-music-at-steel-wheel-tavern\/","url":"https:\/\/thelocalgirl.com\/bergen\/event\/ryan-flannery-live-music-at-steel-wheel-tavern\/","name":"Ryan Flannery - Live Music! at Steel Wheel Tavern - The Bergen County Girl","isPartOf":{"@id":"https:\/\/thelocalgirl.com\/bergen\/#website"},"datePublished":"2026-04-15T23:49:45+00:00","dateModified":"2026-04-17T16:26:46+00:00","breadcrumb":{"@id":"https:\/\/thelocalgirl.com\/bergen\/event\/ryan-flannery-live-music-at-steel-wheel-tavern\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thelocalgirl.com\/bergen\/event\/ryan-flannery-live-music-at-steel-wheel-tavern\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thelocalgirl.com\/bergen\/event\/ryan-flannery-live-music-at-steel-wheel-tavern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thelocalgirl.com\/bergen\/"},{"@type":"ListItem","position":2,"name":"Ryan Flannery &#8211; Live Music! at Steel Wheel Tavern"}]},{"@type":"WebSite","@id":"https:\/\/thelocalgirl.com\/bergen\/#website","url":"https:\/\/thelocalgirl.com\/bergen\/","name":"The Bergen County Girl","description":"A lifestyle site dedicated to all things Local \u2014 with a New Jersey twist.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thelocalgirl.com\/bergen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/thelocalgirl.com\/bergen\/wp-json\/wp\/v2\/event\/237817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thelocalgirl.com\/bergen\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/thelocalgirl.com\/bergen\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/thelocalgirl.com\/bergen\/wp-json\/wp\/v2\/users\/422"}],"wp:attachment":[{"href":"https:\/\/thelocalgirl.com\/bergen\/wp-json\/wp\/v2\/media?parent=237817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thelocalgirl.com\/bergen\/wp-json\/wp\/v2\/categories?post=237817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thelocalgirl.com\/bergen\/wp-json\/wp\/v2\/tags?post=237817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}